{"id":2246,"date":"2020-11-18T11:23:15","date_gmt":"2020-11-18T10:23:15","guid":{"rendered":"https:\/\/arem.it\/?page_id=2246"},"modified":"2021-03-09T10:39:07","modified_gmt":"2021-03-09T09:39:07","slug":"cucito-e-confezioni","status":"publish","type":"page","link":"https:\/\/arem.it\/it\/i-servizi\/cucito-e-confezioni\/","title":{"rendered":"Cucito e confezioni"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><span style=\"color:#19a300\" class=\"has-inline-color\"><a href=\"https:\/\/youtu.be\/Y_L0b9IibPk\" target=\"_blank\" rel=\"noreferrer noopener\">Arem Italia<\/a><\/span><\/strong> dal 1979 offre un servizio di ricamo e personalizzazione per abbigliamento e tessuti. L&#8217;esperienza del personale e le tecnologie e macchinari di nuova generazione garantiscono ricami, stampe, applicazioni di qualit\u00e0 dal piccolo al grande formato, partendo sempre dal servizio grafico con il disegno del logo.<br>I servizi sono forniti per molti settori di mercato, dal promozionale allo sportivo, dall&#8217;abbigliamento da lavoro all&#8217;arredamento, dall&#8217; auto motive alla meccanica, dal settore istituzionale a quello religioso, fino a quello alimentare e dell&#8217;estetica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arem Italia dal 1979 offre un servizio di ricamo e personalizzazione per abbigliamento e tessuti. L&#8217;esperienza del personale e le tecnologie e macchinari di nuova generazione garantiscono ricami, stampe, applicazioni di qualit\u00e0 dal piccolo al grande formato, partendo sempre dal servizio grafico con il disegno del logo.I servizi sono forniti per molti settori di mercato, [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/arem.it\/it\/i-servizi\/cucito-e-confezioni\/\">Leggi di pi\u00f9&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":42,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2246","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/2246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/comments?post=2246"}],"version-history":[{"count":4,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/2246\/revisions"}],"predecessor-version":[{"id":2791,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/2246\/revisions\/2791"}],"up":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/42"}],"wp:attachment":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/media?parent=2246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}