{"id":2371,"date":"2020-11-23T14:54:27","date_gmt":"2020-11-23T13:54:27","guid":{"rendered":"https:\/\/arem.it\/?page_id=2371"},"modified":"2026-03-30T11:33:17","modified_gmt":"2026-03-30T09:33:17","slug":"arte-design","status":"publish","type":"page","link":"https:\/\/arem.it\/it\/arte-design\/","title":{"rendered":"Arte &#038; Design"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pagina dedicata alle personalizzazioni tessili pi\u00f9 speciali che esistono, il meglio dei ricami e delle stampe abbinati per creare effetti splendidi e unici, dedicati al settore Home Textile e Outdoor Living Textile. Realizzazioni uniche o multiple, con fili speciali, su bellissimi tessuti a richiesta e con disegni o scritte di qualsiasi dimensione. Immergiti in questo mondo di idee e arte, mandaci il tuo progetto e ti faremo un&#8217;offerta gratuita accompagnata da un realistico moke up di presentazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pagina dedicata alle personalizzazioni tessili pi\u00f9 speciali che esistono, il meglio dei ricami e delle stampe abbinati per creare effetti splendidi e unici, dedicati al settore Home Textile e Outdoor Living Textile. Realizzazioni uniche o multiple, con fili speciali, su bellissimi tessuti a richiesta e con disegni o scritte di qualsiasi dimensione. Immergiti in questo [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/arem.it\/it\/arte-design\/\">Leggi di pi\u00f9&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2371","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/2371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/comments?post=2371"}],"version-history":[{"count":5,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/2371\/revisions"}],"predecessor-version":[{"id":5268,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/2371\/revisions\/5268"}],"wp:attachment":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/media?parent=2371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}