{"id":44,"date":"2019-02-14T11:18:08","date_gmt":"2019-02-14T10:18:08","guid":{"rendered":"http:\/\/arem.it.staging.guermandi.it\/?page_id=44"},"modified":"2019-02-21T14:19:09","modified_gmt":"2019-02-21T13:19:09","slug":"il-laboratorio","status":"publish","type":"page","link":"https:\/\/arem.it\/it\/il-laboratorio\/","title":{"rendered":"Il Laboratorio"},"content":{"rendered":"\n<div class=\"wp-block-columns has-2-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">La nostra mission<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Arem Italia vuole raggiungere <strong>un alto grado di soddisfazione dei clienti<\/strong> che desiderano avere un personalizzazione di qualit\u00e0 su tutto il tessile, investendo nei prossimi anni risorse e denaro per favorire il benessere di collaboratori, fornitori e dipendenti che possano conciliare famiglia\/lavoro\/tempo libero, crescita aziendale, cercando di <strong>creare un ambiente lavorativo sempre pi\u00f9 eco-sostenibile<\/strong>\u00a0e nel rispetto della natura. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acquistando da noi, sostieni queste iniziative e hai la garanzia di un partner affidabile.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/arem.it.staging.guermandi.it\/wp-content\/uploads\/2019\/02\/IMG_1183-1024x576.jpg\" alt=\"\" class=\"wp-image-479\" srcset=\"https:\/\/arem.it\/wp-content\/uploads\/2019\/02\/IMG_1183-1024x576.jpg 1024w, https:\/\/arem.it\/wp-content\/uploads\/2019\/02\/IMG_1183-300x169.jpg 300w, https:\/\/arem.it\/wp-content\/uploads\/2019\/02\/IMG_1183-768x432.jpg 768w, https:\/\/arem.it\/wp-content\/uploads\/2019\/02\/IMG_1183.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns has-2-columns grigio is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/arem.it.staging.guermandi.it\/wp-content\/uploads\/2019\/02\/IMG_1188-1-1024x576.jpg\" alt=\"\" class=\"wp-image-477\" srcset=\"https:\/\/arem.it\/wp-content\/uploads\/2019\/02\/IMG_1188-1-1024x576.jpg 1024w, https:\/\/arem.it\/wp-content\/uploads\/2019\/02\/IMG_1188-1-300x169.jpg 300w, https:\/\/arem.it\/wp-content\/uploads\/2019\/02\/IMG_1188-1-768x432.jpg 768w, https:\/\/arem.it\/wp-content\/uploads\/2019\/02\/IMG_1188-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">I Laboratori<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">I diversi laboratori <strong>sono dislocati in Italia e nel mondo<\/strong>, dispongono di macchine automatiche da ricamo, giostre serigrafiche, plotter, taglio laser, macchine industriali da cucire e la tecnologia di Industria 4.0 <strong>per creare personalizzazioni su tessile e abbigliamento per la \u00a0soddisfazione del cliente<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anche a livello di software si utilizzano tutti i programmi sul mercato, sempre aggiornati alle esigenze dei clienti. Se sei nostro partner, il nostro staff ti aspetta per una visita ai laboratori.<br><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La nostra mission Arem Italia vuole raggiungere un alto grado di soddisfazione dei clienti che desiderano avere un personalizzazione di qualit\u00e0 su tutto il tessile, investendo nei prossimi anni risorse e denaro per favorire il benessere di collaboratori, fornitori e dipendenti che possano conciliare famiglia\/lavoro\/tempo libero, crescita aziendale, cercando di creare un ambiente lavorativo sempre [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/arem.it\/it\/il-laboratorio\/\">Leggi di pi\u00f9&#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-44","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":7,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/44\/revisions"}],"predecessor-version":[{"id":515,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/44\/revisions\/515"}],"wp:attachment":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/media?parent=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}