{"id":491,"date":"2019-02-19T16:55:47","date_gmt":"2019-02-19T15:55:47","guid":{"rendered":"http:\/\/arem.it.staging.guermandi.it\/?page_id=491"},"modified":"2020-11-26T15:39:19","modified_gmt":"2020-11-26T14:39:19","slug":"personalizzazioni-standard","status":"publish","type":"page","link":"https:\/\/arem.it\/it\/i-servizi\/personalizzazioni-standard\/","title":{"rendered":"Personalizzazioni ricamate"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Arem Italia dal 1979 propone ai clienti un servizio di ricami e personalizzazioni per abbigliamento e tessile<\/strong>. L\u2019esperienza dello staff, le tecnologie e i macchinari di nuova generazione garantiscono ricami, stampe, applicazioni di qualit\u00e0 con varie tipologie di formati,\u00a0 dalle piccole dimensioni ai grandi formati, sempre partendo dal servizio grafico con la progettazione del logo.\u00a0<br>Si forniscono servizi di stampa su divise per molti settori di mercato, dal promozionale allo sportivo, dall\u2019abbigliamento da lavoro all\u2019arredo, dall\u2019automotive alla meccanica, dal settore istituzionale al religioso, fino ai settori food ed estetica. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arem Italia dal 1979 propone ai clienti un servizio di ricami e personalizzazioni per abbigliamento e tessile. L\u2019esperienza dello staff, le tecnologie e i macchinari di nuova generazione garantiscono ricami, stampe, applicazioni di qualit\u00e0 con varie tipologie di formati,\u00a0 dalle piccole dimensioni ai grandi formati, sempre partendo dal servizio grafico con la progettazione del logo.\u00a0Si [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/arem.it\/it\/i-servizi\/personalizzazioni-standard\/\">Leggi di pi\u00f9&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":42,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-491","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/comments?post=491"}],"version-history":[{"count":12,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/491\/revisions"}],"predecessor-version":[{"id":2428,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/491\/revisions\/2428"}],"up":[{"embeddable":true,"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/pages\/42"}],"wp:attachment":[{"href":"https:\/\/arem.it\/it\/wp-json\/wp\/v2\/media?parent=491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}